{"id":8742,"date":"2024-07-19T12:50:07","date_gmt":"2024-07-19T11:50:07","guid":{"rendered":"https:\/\/kamforsud.org\/changement-climatique\/"},"modified":"2026-06-30T16:49:15","modified_gmt":"2026-06-30T15:49:15","slug":"changement-climatique","status":"publish","type":"page","link":"https:\/\/kamforsud.org\/fr\/changement-climatique\/","title":{"rendered":"Changements climatiques"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8742\" class=\"elementor elementor-8742 elementor-1929\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ae70c8c e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"1ae70c8c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7cab55a5 e-con-full e-flex e-con e-child\" data-id=\"7cab55a5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f2249ef elementor-widget elementor-widget-site-logo\" data-id=\"4f2249ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;width&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;width_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;align&quot;:&quot;center&quot;,&quot;width_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;space&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;space_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;space_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;image_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;image_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_space&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;caption_space_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;caption_space_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"site-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hfe-site-logo\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"\"  class='elementor-clickable' href=\"https:\/\/kamforsud.org\/fr\/\">\n\t\t\t\t\t\t\t<div class=\"hfe-site-logo-set\">           \n\t\t\t\t<div class=\"hfe-site-logo-container\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"hfe-site-logo-img elementor-animation-\"  src=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/07\/03-logo-kfs-2-768x218.png\" alt=\"03 logo kfs\"\/>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>  \n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f178682 elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"6f178682\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\"\n\t\t\tdata-hamburger-icon=\"icon icon-menu-11\"\n\t\t\tdata-hamburger-icon-type=\"icon\"\n\t\t\tdata-responsive-breakpoint=\"1024\"\n\t\t\tdata-close-on-anchor=\"no\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\"  type=\"button\" aria-label=\"hamburger-icon\">\n                <i aria-hidden=\"true\" class=\"ekit-menu-icon icon icon-menu-11\"><\/i>            <\/button>\n            <div id=\"ekit-megamenu-menu-header\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page- ekit-nav-dropdown-hover\"><ul id=\"menu-menu-header-francese\" class=\"elementskit-navbar-nav elementskit-menu-po-center submenu-click-on-\"><li id=\"menu-item-9334\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9334 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"#\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">\u00c0 propos<i aria-hidden=\"true\" class=\"icon icon-none elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-9364\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9364 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/apercu-de-kam-for-sud\/\" class=\" dropdown-item\">Kam For Sud en bref<\/a>\t<li id=\"menu-item-9365\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9365 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/comites\/\" class=\" dropdown-item\">Comit\u00e9s<\/a>\t<li id=\"menu-item-9366\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9366 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/histoire-de-kam-for-sud\/\" class=\" dropdown-item\">Histoire de Kam For Sud<\/a>\t<li id=\"menu-item-9367\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9367 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/statuts-budgets-et-rapports\/\" class=\" dropdown-item\">Statuts, bilans et rapports<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-9340\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9340 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"#\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Projets<i aria-hidden=\"true\" class=\"icon icon-none elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-9368\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9368 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"#\" class=\" dropdown-item\">Projets en cours<i aria-hidden=\"true\" class=\"icon icon-none elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-9369\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9369 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/parrainages-a-distance\/\" class=\" dropdown-item\">Parrainages \u00e0 distance<\/a>\t\t<li id=\"menu-item-9370\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9370 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/centre-daccueil-de-jour\/\" class=\" dropdown-item\">Centre de jour<\/a>\t\t<li id=\"menu-item-9371\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9371 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/ferme-orphelinat\/\" class=\" dropdown-item\">Orphelinat-ferme<\/a>\t\t<li id=\"menu-item-9372\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9372 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/changement-climatique\/\" class=\" dropdown-item\">Changements climatiques<\/a>\t\t<li id=\"menu-item-9373\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9373 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/mode-ethique\/\" class=\" dropdown-item\">Mode \u00e9thique<\/a>\t\t<li id=\"menu-item-9374\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9374 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/hotel-entreprise-sociale\/\" class=\" dropdown-item\">H\u00f4tel-entreprise sociale<\/a>\t<\/ul>\n\t<li id=\"menu-item-9341\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9341 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"#\" class=\" dropdown-item\">Projets achev\u00e9s<i aria-hidden=\"true\" class=\"icon icon-none elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-9375\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9375 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/ecole-de-saipu\/\" class=\" dropdown-item\">\u00c9cole de Saipu<\/a>\t\t<li id=\"menu-item-9376\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9376 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/sante-publique-a-saipu\/\" class=\" dropdown-item\">Sant\u00e9 publique \u00e0 Saipu<\/a>\t\t<li id=\"menu-item-9377\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9377 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/tissus-traditionnels-de-dhaka\/\" class=\" dropdown-item\">Tissus traditionnels Dhaka<\/a>\t\t<li id=\"menu-item-9378\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9378 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/urgence-pandemique\/\" class=\" dropdown-item\">Urgence pand\u00e9mique<\/a>\t\t<li id=\"menu-item-9379\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9379 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/urgence-et-reconstruction-apres-un-tremblement-de-terre\/\" class=\" dropdown-item\">Urgence et reconstruction apr\u00e8s le tremblement de terre<\/a>\t\t<li id=\"menu-item-9408\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9408 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/micro-turbines\/\" class=\" dropdown-item\">Micro-turbines<\/a>\t<\/ul>\n<\/ul>\n<\/li>\n<li id=\"menu-item-9409\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9409 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/dons\/\" class=\"ekit-menu-nav-link\">Dons<\/a><\/li>\n<li id=\"menu-item-9410\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9410 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/visiter-le-nepal\/\" class=\"ekit-menu-nav-link\">Visiter le N\u00e9pal<\/a><\/li>\n<li id=\"menu-item-9411\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9411 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/video\/\" class=\"ekit-menu-nav-link\">Vid\u00e9o<\/a><\/li>\n<li id=\"menu-item-9412\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9412 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/contact\/\" class=\"ekit-menu-nav-link\">Contact<\/a><\/li>\n<li id=\"menu-item-9342\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9342 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"http:\/\/Shop\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Shop<i aria-hidden=\"true\" class=\"icon icon-none elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-9413\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9413 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/bazaar-et-boutique\/\" class=\" dropdown-item\">Bazar et boutique<\/a>\t<li id=\"menu-item-9343\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-9343 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/shop.kamforsud.org\/\" class=\" dropdown-item\">Online Shop Wear With Ease<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-wpml-ls-3-it\" class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-it wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-3-it nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a title=\"Passer \u00e0 Italien\" href=\"https:\/\/kamforsud.org\/\" class=\"ekit-menu-nav-link\" aria-label=\"Passer \u00e0 Italien\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/kamforsud.org\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/it.svg\"\n            alt=\"Italien\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<li id=\"menu-item-wpml-ls-3-en\" class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-3-en nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a title=\"Passer \u00e0 Anglais\" href=\"https:\/\/kamforsud.org\/en\/\" class=\"ekit-menu-nav-link\" aria-label=\"Passer \u00e0 Anglais\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/kamforsud.org\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/en.svg\"\n            alt=\"Anglais\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ecbda62 e-flex e-con-boxed e-con e-parent\" data-id=\"3ecbda62\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78ef6fc elementor-widget elementor-widget-heading\" data-id=\"78ef6fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">depuis 2012<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3307d3a0 elementor-widget elementor-widget-heading\" data-id=\"3307d3a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Partir ou rester ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f8845a elementor-widget elementor-widget-heading\" data-id=\"3f8845a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b style=\"font-family:\"><span lang=\"IT\" style=\"font-size: 14pt;font-family: Helvetica\">Changement climatique dans le Haut Mustang et strat\u00e9gies d'adaptation<\/span><\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7883c8d elementor-widget elementor-widget-video\" data-id=\"7883c8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=bo3Jd_t7Acc&quot;,&quot;video_type&quot;:&quot;youtube&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58ea7db3 elementor-widget elementor-widget-text-editor\" data-id=\"58ea7db3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span lang=\"IT\" style=\"font-family: Helvetica;\">Le changement climatique a un impact important sur le r\u00e9gime des eaux dans la r\u00e9gion de l&rsquo;Himalaya. En particulier, certains villages du Haut Mustang sont confront\u00e9s \u00e0 un risque accru de glissements de terrain et d&rsquo;inondations pendant la mousson et \u00e0 une diminution significative de la quantit\u00e9 d&rsquo;eau disponible pour l&rsquo;irrigation des champs au printemps, en raison d&rsquo;une r\u00e9duction des r\u00e9serves de neige dans les montagnes. Cette situation a incit\u00e9 trois villages \u00e0 consid\u00e9rer de se d\u00e9placer vers des zones plus fertiles et plus s\u00fbres.<\/span><\/p><p>&nbsp;<\/p><p><span lang=\"IT\" style=\"font-family: Helvetica;\">Consid\u00e9rant que la relocalisation d&rsquo;une communaut\u00e9 enti\u00e8re soul\u00e8ve de nombreuses questions (sentiment d&rsquo;appartenance, conflits pour l&rsquo;acc\u00e8s aux ressources, distribution des nouvelles terres, etc.), et qu&rsquo;elle peut \u00eatre plus complexe qu&rsquo;initialement imagin\u00e9e, ce projet vise \u00e0 identifier la strat\u00e9gie la plus appropri\u00e9e et la plus durable pour faire face au d\u00e9fi climatique, en r\u00e9pondant \u00e0 la question suivante&nbsp;: \u00ab&nbsp;est-il appropri\u00e9 de relocaliser tout un village ou non&nbsp;? Si oui, dans quelles conditions cela peut-il \u00eatre r\u00e9alis\u00e9 avec succ\u00e8s&nbsp;? Dans le cas contraire, quelle est l&rsquo;alternative pour r\u00e9soudre les probl\u00e8mes sur place&nbsp;?&nbsp;\u00bb.<\/span><\/p><p>&nbsp;<\/p><p>Dans un premier temps, Kam For Sud, en collaboration avec l&rsquo;Institut des Sciences de la Terre de la SUPSI et la <em>Lo Mustang Foundation<\/em>, a donc \u00e9tudi\u00e9 la situation dans trois villages gravement touch\u00e9s par la crise de l&rsquo;eau&nbsp;: Samdzong, Yara et Dheye. Un groupe de travail pluridisciplinaire a analys\u00e9 les possibilit\u00e9s d&rsquo;att\u00e9nuer les p\u00e9nuries d&rsquo;eau et les risques naturels au moyen d&rsquo;interventions techniques sur place, en \u00e9tudiant les donn\u00e9es et les mod\u00e8les m\u00e9t\u00e9orologiques et climatiques et en comparant un certain nombre de param\u00e8tres de l&rsquo;endroit d&rsquo;origine avec le site de relocalisation pr\u00e9vu. Toutes les familles concern\u00e9es ont \u00e9galement \u00e9t\u00e9 interpel\u00e9es afin d&rsquo;\u00e9valuer aussi les aspects socioculturels.<\/p><p>&nbsp;<\/p><p>Les trois villages de Samdzong, Yara et Dheye d\u00e9pendent des sources d&rsquo;eau d&rsquo;origine nivale. Or, en raison du r\u00e9chauffement climatique, il y a de moins en moins de neige, et comme les ressources en eau disponibles sont d\u00e9j\u00e0 pleinement utilis\u00e9es, il n&rsquo;y a pas de marge pour compenser la r\u00e9duction de la masse neigeuse. Le groupe de travail a identifi\u00e9 des mesures techniques pour am\u00e9liorer les captages, r\u00e9duire les pertes le long des canaux d&rsquo;irrigation et am\u00e9liorer la m\u00e9thode de distribution de l&rsquo;eau aux diff\u00e9rents terrains, ce qui permet un gain d&rsquo;eau significatif. Cependant, l&rsquo;\u00e9tude des donn\u00e9es et des mod\u00e8les climatiques a fourni un sc\u00e9nario dramatique pour le Mustang&nbsp;: une augmentation de la temp\u00e9rature de 6 \u00e0 10 degr\u00e9s est attendue d&rsquo;ici la fin du si\u00e8cle. Face \u00e0 cette r\u00e9alit\u00e9, les mesures techniques possibles ne r\u00e9soudraient le probl\u00e8me qu&rsquo;\u00e0 court terme, et la question se poserait \u00e0 nouveau dans un avenir plus ou moins proche.<\/p><p>&nbsp;<\/p><p>Il semble donc impossible pour Samdzong et Dheye de s&rsquo;adapter \u00e0 leur habitat actuel en r\u00e9duisant la quantit\u00e9 d&rsquo;eau disponible, c&rsquo;est-\u00e0-dire en r\u00e9duisant la productivit\u00e9 agricole. Des trois, Yara est le seul village qui pourrait parvenir \u00e0 r\u00e9duire la consommation d&rsquo;eau, et donc la production agricole, en diversifiant ses activit\u00e9s \u00e9conomiques, gr\u00e2ce \u00e0 sa situation g\u00e9ographique le long d&rsquo;une route touristique.<\/p><p>&nbsp;<\/p><p>Les habitants de Samdzong et de Dheye ont d\u00e9cid\u00e9 de s&rsquo;installer respectivement sur les terres de Namashung, (bassin versant&nbsp;six fois plus grand que celui de Samdzong) et de Thangchung, (bassin versant trente-six fois plus grand que celui de Dheye), les deux aliment\u00e9es par des sources d&rsquo;origine au moins partiellement glaciaire. Cela assurera une quantit\u00e9 d&rsquo;eau suffisante pour les villages, en tout cas jusqu&rsquo;\u00e0 la fin du si\u00e8cle et probablement m\u00eame au-del\u00e0. Bien que les anciens des deux communaut\u00e9s quittent leur village \u00e0 contrec\u0153ur, la forte coh\u00e9sion sociale, le sens profond de la communaut\u00e9 et l&rsquo;inqui\u00e9tude pour l&rsquo;avenir de la jeune g\u00e9n\u00e9ration les incitent \u00e0 s&rsquo;adapter \u00e0 la d\u00e9cision de la majorit\u00e9.<\/p><p>&nbsp;<\/p><p>Pour assurer l&rsquo;approvisionnement en eau (eau potable et eau d&rsquo;irrigation pour les champs) dans le nouveau village de Dheye et am\u00e9liorer la collecte et la distribution de l&rsquo;eau \u00e0 Yara, Kam For Sud a fourni des conseils techniques sp\u00e9cifiques dans le cadre d&rsquo;une deuxi\u00e8me phase de projet.<\/p><p>&nbsp;<\/p><p>Kam For Sud s&rsquo;est distanci\u00e9 du projet de relocalisation de Samdzong au motif que le site propos\u00e9 pour la nouvelle implantation a \u00e9t\u00e9 jug\u00e9 dangereux. Il existe en fait un risque d&rsquo;effondrement d&rsquo;un lac glaciaire en amont, qui provoquerait une grave inondation soudaine. D&rsquo;autre part, deux coul\u00e9es de d\u00e9bris attribuables \u00e0 l&rsquo;effondrement de lacs glaciaires dans le bassin de la Chumaka Khola (survenues en 1984 et 1987) ont d\u00e9j\u00e0 envahi la zone d\u00e9sign\u00e9e pour les futurs camps de Namashung avec du gravier et des blocs d&rsquo;une taille allant jusqu&rsquo;\u00e0 plus de 2 m\u00e8tres cubes.<\/p><p>&nbsp;<\/p><p>Le village de Dheye, avec le soutien d&rsquo;une ONG fran\u00e7aise, a construit un nouveau village \u00e0 Thangchung, tout en conservant l&rsquo;ancien village comme une sorte d&rsquo;alpage.<\/p><p>&nbsp;<\/p><p>Le village de Yara a relev\u00e9 le d\u00e9fi de rester sur ses propres terres et de diversifier ses activit\u00e9s \u00e9conomiques. Dans une troisi\u00e8me phase du projet, Kam For Sud a donc offert aux familles sans terre du village de Yara un troupeau de cent ch\u00e8vres dans le cadre d&rsquo;un programme de microcr\u00e9dit et a mis en place un verger communautaire au profit de l&rsquo;ensemble de la communaut\u00e9.<\/p><p>&nbsp;<\/p><p>Compte tenu de l&rsquo;int\u00e9r\u00eat suscit\u00e9 par le verger dans la r\u00e9gion, en collaboration avec l&rsquo;ONG fran\u00e7aise Bessin-N\u00e9pal, le m\u00eame a ensuite \u00e9t\u00e9 propos\u00e9 aux cinq villages du district&nbsp;: Yara, Ghara, Dheye, Tange, Surkhang\/Dhi. Dix vari\u00e9t\u00e9s diff\u00e9rentes de pommiers ont \u00e9t\u00e9 plant\u00e9es, soit environ quatre-vingts arbres dans chacun des cinq villages. Un accompagnement technique est toujours en cours pour ce qui concerne la gestion des vergers (irrigation, taille, apport d&rsquo;engrais, lutte contre les parasites, greffage).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c39fcf4 elementor-widget elementor-widget-heading\" data-id=\"c39fcf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rapports de travail<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b91347 elementor-widget elementor-widget-text-editor\" data-id=\"5b91347\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLe rapport de travail de la Phase 1 se compose de quatre volumes&nbsp;: un rapport autonome pour chaque village et un rapport de synth\u00e8se. Deux rapports r\u00e9sument le travail effectu\u00e9 au cours de la Phase 2, tandis que pour la Phase 3 un rapport r\u00e9sumant l&rsquo;ensemble du travail a \u00e9t\u00e9 produit en 2019. Tous les rapports peuvent \u00eatre t\u00e9l\u00e9charg\u00e9s ci-dessous&nbsp;:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a770387 elementor-widget elementor-widget-elementskit-tablepress\" data-id=\"a770387\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-tablepress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elemenetskit-tablepress ekit-wid-con\" id=\"ekit_tablepress_a770387\">\n<table id=\"tablepress-23\" class=\"tablepress tablepress-id-23\">\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-1\">\n\t<td class=\"column-1\"><a href=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2017\/08\/Climate-Change-Report-Part-1-Synthesis-1.pdf\" rel=\"noopener\" target=\"_blank\"><i class=\"fa-solid fa-file-pdf\"><\/i> Phase 1 \u2013 Synth\u00e8se (EN)<\/a><\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\"><a href=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2017\/08\/Climate-Change-Report-Part-2-Samzong-1.pdf\" rel=\"noopener\" target=\"_blank\"><i class=\"fa-solid fa-file-pdf\"><\/i> Phase 1 \u2013 Samzong (EN)<\/a><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\"><a href=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2017\/08\/Climate-Change-Report-Part-3-Yara-1.pdf\" rel=\"noopener\" target=\"_blank\"><i class=\"fa-solid fa-file-pdf\"><\/i> Phase 1 \u2013 Yara (EN)<\/a><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\"><a href=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2017\/08\/Climate-Change-Report-Part-4-Dheye-1.pdf\" rel=\"noopener\" target=\"_blank\"><i class=\"fa-solid fa-file-pdf\"><\/i> Phase 1 \u2013 Dheye (EN)<\/a><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\"><a href=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/08\/Report-Phase-II_Yara.pdf\" rel=\"noopener\" target=\"_blank\"><i class=\"fa-solid fa-file-pdf\"><\/i> Phase 2 \u2013 Yara (EN)<\/a><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\"><a href=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/08\/Report-Phase-II_Dheye.pdf\" rel=\"noopener\" target=\"_blank\"><i class=\"fa-solid fa-file-pdf\"><\/i> Phase 2 \u2013 Dheye (EN)<\/a><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\"><a href=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/08\/2019-Mustang-rapport-de-mission-SB.pdf\" rel=\"noopener\" target=\"_blank\"><i class=\"fa-solid fa-file-pdf\"><\/i> Phase 3 \u2013 Rapport (FR)<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c0 propos Kam For Sud en bref Comit\u00e9s Histoire de Kam For Sud Statuts, bilans et rapports Projets Projets en cours Parrainages \u00e0 distance Centre de jour Orphelinat-ferme Changements climatiques Mode \u00e9thique H\u00f4tel-entreprise sociale Projets achev\u00e9s \u00c9cole de Saipu Sant\u00e9 publique \u00e0 Saipu Tissus traditionnels Dhaka Urgence pand\u00e9mique Urgence et reconstruction apr\u00e8s le tremblement de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7965,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8742","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/pages\/8742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/comments?post=8742"}],"version-history":[{"count":31,"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/pages\/8742\/revisions"}],"predecessor-version":[{"id":11114,"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/pages\/8742\/revisions\/11114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/media\/7965"}],"wp:attachment":[{"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/media?parent=8742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}