{"id":8715,"date":"2024-07-31T13:59:15","date_gmt":"2024-07-31T12:59:15","guid":{"rendered":"https:\/\/kamforsud.org\/visiter-le-nepal\/"},"modified":"2026-06-30T16:52:04","modified_gmt":"2026-06-30T15:52:04","slug":"visiter-le-nepal","status":"publish","type":"page","link":"https:\/\/kamforsud.org\/fr\/visiter-le-nepal\/","title":{"rendered":"Visiter le N\u00e9pal"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8715\" class=\"elementor elementor-8715 elementor-5413\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9dfa606 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"9dfa606\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-652da50 e-con-full e-flex e-con e-child\" data-id=\"652da50\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e41fa54 elementor-widget elementor-widget-site-logo\" data-id=\"e41fa54\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;width&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;width_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;align&quot;:&quot;center&quot;,&quot;width_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;space&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;space_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;space_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;image_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;image_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;caption_space&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;caption_space_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;caption_space_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"site-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hfe-site-logo\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"\"  class='elementor-clickable' href=\"https:\/\/kamforsud.org\/fr\/\">\n\t\t\t\t\t\t\t<div class=\"hfe-site-logo-set\">           \n\t\t\t\t<div class=\"hfe-site-logo-container\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"hfe-site-logo-img elementor-animation-\"  src=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/07\/03-logo-kfs-2-768x218.png\" alt=\"03 logo kfs\"\/>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>  \n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76c5f109 elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"76c5f109\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\"\n\t\t\tdata-hamburger-icon=\"icon icon-menu-11\"\n\t\t\tdata-hamburger-icon-type=\"icon\"\n\t\t\tdata-responsive-breakpoint=\"1024\"\n\t\t\tdata-close-on-anchor=\"no\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\"  type=\"button\" aria-label=\"hamburger-icon\">\n                <i aria-hidden=\"true\" class=\"ekit-menu-icon icon icon-menu-11\"><\/i>            <\/button>\n            <div id=\"ekit-megamenu-menu-header\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page- ekit-nav-dropdown-hover\"><ul id=\"menu-menu-header-francese\" class=\"elementskit-navbar-nav elementskit-menu-po-center submenu-click-on-\"><li id=\"menu-item-9334\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9334 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"#\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">\u00c0 propos<i aria-hidden=\"true\" class=\"icon icon-none elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-9364\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9364 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/apercu-de-kam-for-sud\/\" class=\" dropdown-item\">Kam For Sud en bref<\/a>\t<li id=\"menu-item-9365\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9365 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/comites\/\" class=\" dropdown-item\">Comit\u00e9s<\/a>\t<li id=\"menu-item-9366\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9366 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/histoire-de-kam-for-sud\/\" class=\" dropdown-item\">Histoire de Kam For Sud<\/a>\t<li id=\"menu-item-9367\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9367 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/statuts-budgets-et-rapports\/\" class=\" dropdown-item\">Statuts, bilans et rapports<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-9340\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9340 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"#\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Projets<i aria-hidden=\"true\" class=\"icon icon-none elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-9368\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9368 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"#\" class=\" dropdown-item\">Projets en cours<i aria-hidden=\"true\" class=\"icon icon-none elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-9369\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9369 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/parrainages-a-distance\/\" class=\" dropdown-item\">Parrainages \u00e0 distance<\/a>\t\t<li id=\"menu-item-9370\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9370 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/centre-daccueil-de-jour\/\" class=\" dropdown-item\">Centre de jour<\/a>\t\t<li id=\"menu-item-9371\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9371 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/ferme-orphelinat\/\" class=\" dropdown-item\">Orphelinat-ferme<\/a>\t\t<li id=\"menu-item-9372\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9372 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/changement-climatique\/\" class=\" dropdown-item\">Changements climatiques<\/a>\t\t<li id=\"menu-item-9373\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9373 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/mode-ethique\/\" class=\" dropdown-item\">Mode \u00e9thique<\/a>\t\t<li id=\"menu-item-9374\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9374 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/hotel-entreprise-sociale\/\" class=\" dropdown-item\">H\u00f4tel-entreprise sociale<\/a>\t<\/ul>\n\t<li id=\"menu-item-9341\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9341 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"#\" class=\" dropdown-item\">Projets achev\u00e9s<i aria-hidden=\"true\" class=\"icon icon-none elementskit-submenu-indicator\"><\/i><\/a>\n\t<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t\t<li id=\"menu-item-9375\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9375 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/ecole-de-saipu\/\" class=\" dropdown-item\">\u00c9cole de Saipu<\/a>\t\t<li id=\"menu-item-9376\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9376 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/sante-publique-a-saipu\/\" class=\" dropdown-item\">Sant\u00e9 publique \u00e0 Saipu<\/a>\t\t<li id=\"menu-item-9377\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9377 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/tissus-traditionnels-de-dhaka\/\" class=\" dropdown-item\">Tissus traditionnels Dhaka<\/a>\t\t<li id=\"menu-item-9378\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9378 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/urgence-pandemique\/\" class=\" dropdown-item\">Urgence pand\u00e9mique<\/a>\t\t<li id=\"menu-item-9379\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9379 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/urgence-et-reconstruction-apres-un-tremblement-de-terre\/\" class=\" dropdown-item\">Urgence et reconstruction apr\u00e8s le tremblement de terre<\/a>\t\t<li id=\"menu-item-9408\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9408 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/micro-turbines\/\" class=\" dropdown-item\">Micro-turbines<\/a>\t<\/ul>\n<\/ul>\n<\/li>\n<li id=\"menu-item-9409\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9409 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/dons\/\" class=\"ekit-menu-nav-link\">Dons<\/a><\/li>\n<li id=\"menu-item-9410\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9410 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/visiter-le-nepal\/\" class=\"ekit-menu-nav-link\">Visiter le N\u00e9pal<\/a><\/li>\n<li id=\"menu-item-9411\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9411 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/video\/\" class=\"ekit-menu-nav-link\">Vid\u00e9o<\/a><\/li>\n<li id=\"menu-item-9412\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9412 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/contact\/\" class=\"ekit-menu-nav-link\">Contact<\/a><\/li>\n<li id=\"menu-item-9342\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-9342 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"http:\/\/Shop\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Shop<i aria-hidden=\"true\" class=\"icon icon-none elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-9413\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9413 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/kamforsud.org\/fr\/bazaar-et-boutique\/\" class=\" dropdown-item\">Bazar et boutique<\/a>\t<li id=\"menu-item-9343\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-9343 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/shop.kamforsud.org\/\" class=\" dropdown-item\">Online Shop Wear With Ease<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-wpml-ls-3-it\" class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-it wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-3-it nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a title=\"Passer \u00e0 Italien\" href=\"https:\/\/kamforsud.org\/\" class=\"ekit-menu-nav-link\" aria-label=\"Passer \u00e0 Italien\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/kamforsud.org\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/it.svg\"\n            alt=\"Italien\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<li id=\"menu-item-wpml-ls-3-en\" class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-3-en nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a title=\"Passer \u00e0 Anglais\" href=\"https:\/\/kamforsud.org\/en\/\" class=\"ekit-menu-nav-link\" aria-label=\"Passer \u00e0 Anglais\"><img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/kamforsud.org\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/en.svg\"\n            alt=\"Anglais\"\n            loading=\"lazy\"\n            \n            \n    \/><\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ff236ff e-flex e-con-boxed e-con e-parent\" data-id=\"5ff236ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b89cea0 elementor-widget elementor-widget-heading\" data-id=\"7b89cea0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Visiter le N\u00e9pal<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-051fc8e elementor-widget elementor-widget-text-editor\" data-id=\"051fc8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"letter-spacing: -0.1px;\">Voyager au N\u00e9pal, c&rsquo;est avant tout rencontrer la chaleur de son peuple, se confronter au joyeux chaos d&rsquo;une capitale en pleine \u00e9volution mais toujours fid\u00e8le \u00e0 elle-m\u00eame, d\u00e9couvrir au fur et \u00e0 mesure la beaut\u00e9 de ses paysages et de ses montagnes ainsi que la richesse d&rsquo;un patrimoine culturel mill\u00e9naire ; c&rsquo;est s&rsquo;immerger dans un monde au fort parfum d&rsquo;\u00e9pices, d&rsquo;encens et d&rsquo;humanit\u00e9, entre modernit\u00e9 et tradition, qui conserve une \u00e2me capable de s&rsquo;\u00e9merveiller et de surprendre.<\/span><\/p><p>&nbsp;<\/p><p><span style=\"letter-spacing: -0.1px;\">Au c\u0153ur de l&rsquo;ancienne ville de Patan, devenue le quartier m\u00e9ridional de la grande Katmandou, se trouve l&rsquo;<a href=\"http:\/\/www.newachen.com\">h\u00f4tel Newa Chen<\/a>, une perle de beaut\u00e9 architecturale d\u00e9j\u00e0 restaur\u00e9e en 2006 avec des fonds de l&rsquo;UNESCO et qui a fait l&rsquo;objet d&rsquo;une nouvelle restauration en 2022-23, ce qui fait du Newa Chen une oasis de tranquillit\u00e9 dans l&rsquo;effervescence de Patan et un t\u00e9moignage de la vie Newars authentique, sans renoncer au confort.&nbsp;<\/span><span style=\"background-color: var( --e-global-color-secondary ); color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-style: var( --e-global-typography-text-font-style ); font-weight: var( --e-global-typography-text-font-weight ); letter-spacing: var( --e-global-typography-text-letter-spacing ); text-align: var(--text-align); text-transform: var( --e-global-typography-text-text-transform ); word-spacing: var( --e-global-typography-text-word-spacing );\">Il s&rsquo;agit d&rsquo;un h\u00f4tel-entreprise sociale qui offre \u00e0 certains des enfants qui ont grandi dans les structures de Kam For Sud (orphelinat-ferme, centre de jour, parrainages) la possibilit\u00e9 de travailler et d&rsquo;apprendre un m\u00e9tier et qui consacre l&rsquo;int\u00e9gralit\u00e9 de ses b\u00e9n\u00e9fices \u00e0 l&rsquo;orphelinat de Tathali.<\/span><\/p><p>&nbsp;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a57c6be elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"5a57c6be\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/08\/newa-chen-piazzale-1024x683.jpg\" alt=\"newa-chen-piazzale\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/08\/newa-chen-camera-storica-1024x683.jpg\" alt=\"newa-chen-camera-storica\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/08\/newa-chen-lounge-scaled-e1723758141850-1024x674.jpeg\" alt=\"newa-chen-lounge\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/08\/newa-chen-camera-nuova-1024x683.jpg\" alt=\"newa-chen-camera-nuova\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/08\/newa-chen-bagno-1024x683.jpg\" alt=\"newa-chen-bagno\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/08\/newa-chen-finestre-1024x684.jpeg\" alt=\"newa-chen-finestre\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-left\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M257.5 445.1l-22.2 22.2c-9.4 9.4-24.6 9.4-33.9 0L7 273c-9.4-9.4-9.4-24.6 0-33.9L201.4 44.7c9.4-9.4 24.6-9.4 33.9 0l22.2 22.2c9.5 9.5 9.3 25-.4 34.3L136.6 216H424c13.3 0 24 10.7 24 24v32c0 13.3-10.7 24-24 24H136.6l120.5 114.8c9.8 9.3 10 24.8.4 34.3z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b2e5f75 elementor-widget elementor-widget-text-editor\" data-id=\"6b2e5f75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><span style=\"background-color: var( --e-global-color-secondary ); color: var( --e-global-color-text ); letter-spacing: -0.1px; text-align: var(--text-align);\">L&rsquo;<a href=\"http:\/\/www.newachen.com\">h\u00f4tel Newa Chen<\/a> est le point de d\u00e9part id\u00e9al pour visiter la vall\u00e9e de Katmandou tout en soutenant de nombreux jeunes N\u00e9palais dans leur parcours professionnel et de vie<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7b6184 elementor-widget elementor-widget-text-editor\" data-id=\"b7b6184\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les membres et donateur de Kam For Sud qui souhaitent visiter le N\u00e9pal et les projets de l&rsquo;association peuvent nous contacter \u00e0 l&rsquo;adresse info@kamforsud.org s&rsquo;ils souhaitent une assistance dans l&rsquo;organisation de leur voyage ou d&rsquo;une visite sp\u00e9cifique.<\/p><p>&nbsp;<\/p><p>&nbsp;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee8304b elementor-widget elementor-widget-heading\" data-id=\"ee8304b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le centre historique de Patan<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cdfda7 elementor-widget elementor-widget-text-editor\" data-id=\"5cdfda7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La ville historique de Patan est un fascinant r\u00e9seau de ruelles et de cours, de temples et de palais, d&rsquo;ateliers d&rsquo;artisans et d&rsquo;artistes, de bars, de caf\u00e9s, de restaurants et de petits tr\u00e9sors cach\u00e9s que le visiteur peut d\u00e9couvrir en se promenant dans la ville sans h\u00e2te et avec respect. Voici quelques conseils.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-942e7ba elementor-widget elementor-widget-heading\" data-id=\"942e7ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Durbar Square<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2708225 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"2708225\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 1\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/08\/Durbar-square-1-1024x806.jpg\" alt=\"Durbar square\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3698c3d elementor-widget elementor-widget-text-editor\" data-id=\"3698c3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le&nbsp;<i>Durbar Square<\/i>&nbsp;est l&rsquo;un des sept sites de la vall\u00e9e de Katmandou inscrits au patrimoine mondial de l&rsquo;Unesco. Avec ses temples de diff\u00e9rentes typologies architecturales, son palais royal, ses pagodes et ses fontaines publiques, la place des temples est une vitrine de l&rsquo;architecture newar, qui a atteint son apog\u00e9e sous le r\u00e8gne des Malla. La belle place de Patan est \u00e0 son meilleur t\u00f4t le matin et au cr\u00e9puscule, lorsque la plupart des visiteurs ne sont pas encore arriv\u00e9s ou sont d\u00e9j\u00e0 partis, et qu&rsquo;elle peut donc accueillir les activit\u00e9s quotidiennes des habitants de la ville : ablutions matinales, rituels, sorties du soir, discussions de quartier, march\u00e9, etc.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3aa662 elementor-widget elementor-widget-heading\" data-id=\"d3aa662\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Temple de Baglamukhi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a91c37 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"5a91c37\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 1\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/08\/Kumbeswar-1024x768.jpg\" alt=\"Kumbeswar\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c524abe elementor-widget elementor-widget-text-editor\" data-id=\"c524abe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le <i>temple Baglamukhi&nbsp;<\/i>est d\u00e9di\u00e9 \u00e0 la d\u00e9esse qui a tu\u00e9 le d\u00e9mon Bagla et qui a le pouvoir de faire taire les mauvaises langues, de prot\u00e9ger contre les ennemis, de gagner des proc\u00e8s et, plus g\u00e9n\u00e9ralement, de chasser la malchance. C&rsquo;est en effet une divinit\u00e9 tantrique tr\u00e8s puissante. Il vaut la peine de visiter ce temple le jeudi, t\u00f4t le matin. Le complexe abrite \u00e9galement le<em>&nbsp;Kumbheshwar<\/em>, un temple construit en 1392 et d\u00e9di\u00e9 \u00e0 Shiva. Il s&rsquo;agit du seul temple \u00e0 cinq toits de Patan et de l&rsquo;un des trois seuls existant encore dans l&rsquo;ensemble du N\u00e9pal. On dit que l&rsquo;eau qui coule dans la cour de ce temple provient du lac sacr\u00e9 de Gosainkunda, situ\u00e9 \u00e0 4 400 m\u00e8tres d&rsquo;altitude. Le jour de Janai Purnima (pleine lune de juillet ou ao\u00fbt), de nombreux fid\u00e8les prennent un bain rituel.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2732745 elementor-widget elementor-widget-heading\" data-id=\"2732745\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mus\u00e9e de Patan<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8a78cf elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"c8a78cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 1\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/08\/Patan-royal-palace-1024x813.jpg\" alt=\"Patan royal palace\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41db353 elementor-widget elementor-widget-text-editor\" data-id=\"41db353\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le <i>mus\u00e9e de Patan&nbsp;<\/i>est situ\u00e9 dans l&rsquo;ancien palais royal, b\u00e2ti au XIVe si\u00e8cle et agrandi aux <span style=\"letter-spacing: -0.1px; font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-style: var( --e-global-typography-text-font-style ); font-weight: var( --e-global-typography-text-font-weight ); text-transform: var( --e-global-typography-text-text-transform ); word-spacing: var( --e-global-typography-text-word-spacing ); text-align: var(--text-align); background-color: var( --e-global-color-secondary ); color: var( --e-global-color-text );\">si\u00e8cles<\/span><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-style: var( --e-global-typography-text-font-style ); font-weight: var( --e-global-typography-text-font-weight ); letter-spacing: var( --e-global-typography-text-letter-spacing ); text-transform: var( --e-global-typography-text-text-transform ); word-spacing: var( --e-global-typography-text-word-spacing ); text-align: var(--text-align); background-color: var( --e-global-color-secondary ); color: var( --e-global-color-text );\"> XVIIe et XVIIIe ; le palais a fait l&rsquo;objet d&rsquo;une excellente restauration dans les ann\u00e9es 1980-90 et d&rsquo;autres pr\u00e9cieux travaux de restructuration au d\u00e9but des ann\u00e9es 2000 (ainsi que d&rsquo;une reconstruction partielle apr\u00e8s le tremblement de terre de 2015).<\/span><span class=\"Apple-converted-space\" style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-style: var( --e-global-typography-text-font-style ); font-weight: var( --e-global-typography-text-font-weight ); letter-spacing: var( --e-global-typography-text-letter-spacing ); text-transform: var( --e-global-typography-text-text-transform ); word-spacing: var( --e-global-typography-text-word-spacing ); text-align: var(--text-align); background-color: var( --e-global-color-secondary ); color: var( --e-global-color-text );\">&nbsp;<\/span><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-style: var( --e-global-typography-text-font-style ); font-weight: var( --e-global-typography-text-font-weight ); letter-spacing: var( --e-global-typography-text-letter-spacing ); text-transform: var( --e-global-typography-text-text-transform ); word-spacing: var( --e-global-typography-text-word-spacing ); text-align: var(--text-align); background-color: var( --e-global-color-secondary ); color: var( --e-global-color-text );\">Le mus\u00e9e m\u00e9rite incontestablement une visite, tant pour la beaut\u00e9 architecturale du b\u00e2timent que pour la richesse des \u0153uvres d&rsquo;art qui y sont expos\u00e9es. Le billet d&rsquo;entr\u00e9e est inclus dans le prix du billet pour la place des temples.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f95bb02 elementor-widget elementor-widget-heading\" data-id=\"f95bb02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Golden Temple<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32b3ff6 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"32b3ff6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 1\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/08\/Golden-Temple-768x1024.jpg\" alt=\"Golden Temple\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc4c7db elementor-widget elementor-widget-text-editor\" data-id=\"bc4c7db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le <em>Temple d&rsquo;Or<\/em>, construit au 12\u00e8me si\u00e8cle, abrite une statue de Bouddha tr\u00e8s v\u00e9n\u00e9r\u00e9e. Ce lieu, comme la plupart des temples, offre la meilleure exp\u00e9rience si vous vous y rendez discr\u00e8tement, seul ou en petit groupe, t\u00f4t le matin.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54e6820 elementor-widget elementor-widget-heading\" data-id=\"54e6820\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mahabuddha<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-246f131 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"246f131\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 1\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kamforsud.org\/wp-content\/uploads\/2024\/08\/Mahabouddha-1019x1024.jpg\" alt=\"Mahabouddha\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11fd879 elementor-widget elementor-widget-text-editor\" data-id=\"11fd879\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il vous faudra peut-\u00eatre chercher un peu pour trouver l&rsquo;entr\u00e9e de la bonne cour, parmi les innombrables ruelles de Patan, mais la visite en vaut la peine : ce temple du XIVe si\u00e8cle est un monument bouddhiste exceptionnel avec des milliers d&rsquo;images de Bouddha sculpt\u00e9es en terre cuite.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6430fb elementor-widget elementor-widget-heading\" data-id=\"b6430fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Veuillez noter que...<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8301383 elementor-widget elementor-widget-text-editor\" data-id=\"8301383\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">La vie au N\u00e9pal suit son propre rythme, dict\u00e9 par de nombreux \u00e9v\u00e9nements inattendus et una grande capacit\u00e9 d&rsquo;improvisation.<\/p>\n<p class=\"p1\"><br><\/p>\n<p class=\"p1\">Pour un occidental qui s&rsquo;aventure dans cette r\u00e9alit\u00e9 si diff\u00e9rente de la sienne, il peut \u00eatre utile de savoir qu&rsquo;avec un peu de patience et de bonne humeur, de nombreux probl\u00e8mes peuvent \u00eatre r\u00e9solus (parfois de mani\u00e8re surprenante). <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c0 propos Kam For Sud en bref Comit\u00e9s Histoire de Kam For Sud Statuts, bilans et rapports Projets Projets en cours Parrainages \u00e0 distance Centre de jour Orphelinat-ferme Changements climatiques Mode \u00e9thique H\u00f4tel-entreprise sociale Projets achev\u00e9s \u00c9cole de Saipu Sant\u00e9 publique \u00e0 Saipu Tissus traditionnels Dhaka Urgence pand\u00e9mique Urgence et reconstruction apr\u00e8s le tremblement de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8715","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/pages\/8715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/comments?post=8715"}],"version-history":[{"count":49,"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/pages\/8715\/revisions"}],"predecessor-version":[{"id":11165,"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/pages\/8715\/revisions\/11165"}],"wp:attachment":[{"href":"https:\/\/kamforsud.org\/fr\/wp-json\/wp\/v2\/media?parent=8715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}